{"id":87428,"date":"2021-06-19T15:39:00","date_gmt":"2021-06-19T13:39:00","guid":{"rendered":"https:\/\/europcarblog.dev.aws.europcar.vwfs-ad\/editorial\/unclassified\/vehicules-electriques-en-france-tout-savoir\/"},"modified":"2021-06-19T15:39:00","modified_gmt":"2021-06-19T13:39:00","slug":"vehicules-electriques-en-france-tout-savoir","status":"publish","type":"post","link":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir","title":{"rendered":"V\u00e9hicules \u00e9lectriques en France : tout savoir"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":76153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[320],"class_list":["post-87428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips","tag-france","tag-electric-car"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00e9hicules \u00e9lectriques en France : tout savoir<\/title>\n<meta name=\"description\" content=\"Explorez la France en voiture \u00e9lectrique : plus de 30 000 bornes de recharge, astuces de voyage et conseils pratiques !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00e9hicules \u00e9lectriques en France : tout savoir\" \/>\n<meta property=\"og:description\" content=\"Explorez la France en voiture \u00e9lectrique : plus de 30 000 bornes de recharge, astuces de voyage et conseils pratiques !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\" \/>\n<meta property=\"og:site_name\" content=\"Europcar Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-19T13:39:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Europcar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Europcar\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\"},\"author\":{\"name\":\"Europcar\",\"@id\":\"https:\/\/www.europcar.fr\/editorial#\/schema\/person\/bf179eadeb082f945339e1e2c7d57e5a\"},\"headline\":\"V\u00e9hicules \u00e9lectriques en France : tout savoir\",\"datePublished\":\"2021-06-19T13:39:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\"},\"wordCount\":7,\"publisher\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial#organization\"},\"image\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg\",\"keywords\":[\"France\",\"Voiture \u00e9lectrique\"],\"articleSection\":[\"Conseils\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\",\"url\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\",\"name\":\"V\u00e9hicules \u00e9lectriques en France : tout savoir\",\"isPartOf\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg\",\"datePublished\":\"2021-06-19T13:39:00+00:00\",\"description\":\"Explorez la France en voiture \u00e9lectrique : plus de 30 000 bornes de recharge, astuces de voyage et conseils pratiques !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage\",\"url\":\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg\",\"contentUrl\":\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg\",\"width\":1440,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"HOME\",\"item\":\"https:\/\/www.europcar.fr\/editorial\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils &amp; Guides\",\"item\":\"https:\/\/www.europcar.fr\/editorial\/category\/tips-and-guides\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseils\",\"item\":\"https:\/\/www.europcar.fr\/editorial\/category\/tips-and-guides\/tips\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"V\u00e9hicules \u00e9lectriques en France : tout savoir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.europcar.fr\/editorial#website\",\"url\":\"https:\/\/www.europcar.fr\/editorial\",\"name\":\"Europcar\",\"description\":\"Conseils de voyage, guides de road trip et conseils sur les v\u00e9hicules\",\"publisher\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.europcar.fr\/editorial?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.europcar.fr\/editorial#organization\",\"name\":\"Europcar\",\"url\":\"https:\/\/www.europcar.fr\/editorial\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.europcar.fr\/editorial#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/Europcar_logo_color.svg\",\"contentUrl\":\"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/Europcar_logo_color.svg\",\"caption\":\"Europcar\"},\"image\":{\"@id\":\"https:\/\/www.europcar.fr\/editorial#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.europcar.fr\/editorial#\/schema\/person\/bf179eadeb082f945339e1e2c7d57e5a\",\"name\":\"Europcar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.europcar.fr\/editorial#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61cf68de3c1e49057f8edd17c00046c142843d5af84415cd3dfa6ac53edf9750?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61cf68de3c1e49057f8edd17c00046c142843d5af84415cd3dfa6ac53edf9750?s=96&d=mm&r=g\",\"caption\":\"Europcar\"},\"sameAs\":[\"https:\/\/europcarblog.dev.aws.europcar.vwfs-ad\"],\"url\":\"https:\/\/www.europcar.fr\/editorial\/author\/lesbonstech\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00e9hicules \u00e9lectriques en France : tout savoir","description":"Explorez la France en voiture \u00e9lectrique : plus de 30 000 bornes de recharge, astuces de voyage et conseils pratiques !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir","og_locale":"fr_FR","og_type":"article","og_title":"V\u00e9hicules \u00e9lectriques en France : tout savoir","og_description":"Explorez la France en voiture \u00e9lectrique : plus de 30 000 bornes de recharge, astuces de voyage et conseils pratiques !","og_url":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir","og_site_name":"Europcar Blog","article_published_time":"2021-06-19T13:39:00+00:00","og_image":[{"width":1440,"height":472,"url":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg","type":"image\/jpeg"}],"author":"Europcar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Europcar"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#article","isPartOf":{"@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir"},"author":{"name":"Europcar","@id":"https:\/\/www.europcar.fr\/editorial#\/schema\/person\/bf179eadeb082f945339e1e2c7d57e5a"},"headline":"V\u00e9hicules \u00e9lectriques en France : tout savoir","datePublished":"2021-06-19T13:39:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir"},"wordCount":7,"publisher":{"@id":"https:\/\/www.europcar.fr\/editorial#organization"},"image":{"@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage"},"thumbnailUrl":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg","keywords":["France","Voiture \u00e9lectrique"],"articleSection":["Conseils"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir","url":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir","name":"V\u00e9hicules \u00e9lectriques en France : tout savoir","isPartOf":{"@id":"https:\/\/www.europcar.fr\/editorial#website"},"primaryImageOfPage":{"@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage"},"image":{"@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage"},"thumbnailUrl":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg","datePublished":"2021-06-19T13:39:00+00:00","description":"Explorez la France en voiture \u00e9lectrique : plus de 30 000 bornes de recharge, astuces de voyage et conseils pratiques !","breadcrumb":{"@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#primaryimage","url":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg","contentUrl":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg","width":1440,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/www.europcar.fr\/editorial\/tips-and-guides\/tips\/vehicules-electriques-en-france-tout-savoir#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"HOME","item":"https:\/\/www.europcar.fr\/editorial"},{"@type":"ListItem","position":2,"name":"Conseils &amp; Guides","item":"https:\/\/www.europcar.fr\/editorial\/category\/tips-and-guides"},{"@type":"ListItem","position":3,"name":"Conseils","item":"https:\/\/www.europcar.fr\/editorial\/category\/tips-and-guides\/tips"},{"@type":"ListItem","position":4,"name":"V\u00e9hicules \u00e9lectriques en France : tout savoir"}]},{"@type":"WebSite","@id":"https:\/\/www.europcar.fr\/editorial#website","url":"https:\/\/www.europcar.fr\/editorial","name":"Europcar","description":"Conseils de voyage, guides de road trip et conseils sur les v\u00e9hicules","publisher":{"@id":"https:\/\/www.europcar.fr\/editorial#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.europcar.fr\/editorial?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.europcar.fr\/editorial#organization","name":"Europcar","url":"https:\/\/www.europcar.fr\/editorial","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.europcar.fr\/editorial#\/schema\/logo\/image\/","url":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/Europcar_logo_color.svg","contentUrl":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/Europcar_logo_color.svg","caption":"Europcar"},"image":{"@id":"https:\/\/www.europcar.fr\/editorial#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.europcar.fr\/editorial#\/schema\/person\/bf179eadeb082f945339e1e2c7d57e5a","name":"Europcar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.europcar.fr\/editorial#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61cf68de3c1e49057f8edd17c00046c142843d5af84415cd3dfa6ac53edf9750?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61cf68de3c1e49057f8edd17c00046c142843d5af84415cd3dfa6ac53edf9750?s=96&d=mm&r=g","caption":"Europcar"},"sameAs":["https:\/\/europcarblog.dev.aws.europcar.vwfs-ad"],"url":"https:\/\/www.europcar.fr\/editorial\/author\/lesbonstech"}]}},"featured_media_url":"https:\/\/www.europcar.fr\/editorial\/wp-content\/uploads\/2024\/12\/wordhero.jpg","_links":{"self":[{"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/posts\/87428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/comments?post=87428"}],"version-history":[{"count":0,"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/posts\/87428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/media\/76153"}],"wp:attachment":[{"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/media?parent=87428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europcar.fr\/editorial\/wp-json\/wp\/v2\/categories?post=87428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}